{"id":1457,"date":"2026-06-09T12:21:34","date_gmt":"2026-06-09T10:21:34","guid":{"rendered":"https:\/\/www.beltingskill.com\/products\/cinghie-trapezoidali-in-poliuretano\/notched-v-belt-85a-smooth-transparent\/"},"modified":"2026-08-06T11:53:44","modified_gmt":"2026-08-06T09:53:44","slug":"cinghia-trapezoidale-dentata-85a-liscia-trasparente","status":"publish","type":"products","link":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/","title":{"rendered":"Cinghia trapezoidale dentata 85A liscia trasparente"},"content":{"rendered":"","protected":false},"featured_media":983,"parent":1442,"menu_order":0,"template":"","products-cat":[],"typologies":[57],"class_list":["post-1457","products","type-products","status-publish","has-post-thumbnail","hentry","typologies-cinghia-v-dentellata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/\" \/>\n<meta property=\"og:site_name\" content=\"BeltingSkill\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T09:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.beltingskill.com\/wp-content\/uploads\/2026\/06\/85A-notched-trasparente.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/\",\"url\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/\",\"name\":\"Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.beltingskill.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/85A-notched-trasparente.webp\",\"datePublished\":\"2026-06-09T10:21:34+00:00\",\"dateModified\":\"2026-08-06T09:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.beltingskill.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/85A-notched-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.beltingskill.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/85A-notched-trasparente.webp\",\"width\":835,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/pagina-di-esempio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cinghie trapezoidali in poliuretano\",\"item\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/cinghie-trapezoidali-in-poliuretano\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cinghia trapezoidale dentata 85A liscia trasparente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/\",\"name\":\"BeltingSkill\",\"description\":\"Profili e componenti per sistemi di movimentazione industriale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.beltingskill.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/","og_locale":"it_IT","og_type":"article","og_title":"Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill","og_url":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/","og_site_name":"BeltingSkill","article_modified_time":"2026-08-06T09:53:44+00:00","og_image":[{"width":835,"height":425,"url":"https:\/\/www.beltingskill.com\/wp-content\/uploads\/2026\/06\/85A-notched-trasparente.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/","url":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/","name":"Cinghia trapezoidale dentata 85A liscia trasparente - BeltingSkill","isPartOf":{"@id":"https:\/\/www.beltingskill.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/#primaryimage"},"image":{"@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.beltingskill.com\/wp-content\/uploads\/2026\/06\/85A-notched-trasparente.webp","datePublished":"2026-06-09T10:21:34+00:00","dateModified":"2026-08-06T09:53:44+00:00","breadcrumb":{"@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/#primaryimage","url":"https:\/\/www.beltingskill.com\/wp-content\/uploads\/2026\/06\/85A-notched-trasparente.webp","contentUrl":"https:\/\/www.beltingskill.com\/wp-content\/uploads\/2026\/06\/85A-notched-trasparente.webp","width":835,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/cinghia-trapezoidale-dentata-85a-liscia-trasparente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.beltingskill.com\/it\/pagina-di-esempio\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.beltingskill.com\/it\/products\/"},{"@type":"ListItem","position":3,"name":"Cinghie trapezoidali in poliuretano","item":"https:\/\/www.beltingskill.com\/it\/cinghie-trapezoidali-in-poliuretano\/"},{"@type":"ListItem","position":4,"name":"Cinghia trapezoidale dentata 85A liscia trasparente"}]},{"@type":"WebSite","@id":"https:\/\/www.beltingskill.com\/it\/#website","url":"https:\/\/www.beltingskill.com\/it\/","name":"BeltingSkill","description":"Profili e componenti per sistemi di movimentazione industriale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.beltingskill.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/products\/1457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/types\/products"}],"up":[{"embeddable":true,"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/products\/1442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/media\/983"}],"wp:attachment":[{"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/media?parent=1457"}],"wp:term":[{"taxonomy":"products-cat","embeddable":true,"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/products-cat?post=1457"},{"taxonomy":"typologies","embeddable":true,"href":"https:\/\/www.beltingskill.com\/it\/wp-json\/wp\/v2\/typologies?post=1457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}